{"id":2997,"date":"2020-05-06T19:41:26","date_gmt":"2020-05-06T19:41:26","guid":{"rendered":"https:\/\/www.graphn.com.br\/amaralefazla\/beneficio-emergencial-empregado-tem-que-ficar-de-olho-no-patrao-para-nao-perder-ajuda-do-governo\/"},"modified":"2020-05-06T19:41:26","modified_gmt":"2020-05-06T19:41:26","slug":"beneficio-emergencial-empregado-tem-que-ficar-de-olho-no-patrao-para-nao-perder-ajuda-do-governo","status":"publish","type":"post","link":"https:\/\/www.amaralfazla.com.br\/site\/beneficio-emergencial-empregado-tem-que-ficar-de-olho-no-patrao-para-nao-perder-ajuda-do-governo\/","title":{"rendered":"Benef\u00edcio emergencial: empregado tem que ficar de olho no patr\u00e3o para n\u00e3o perder ajuda do governo"},"content":{"rendered":"<p style=\"text-align: justify;\">O pagamento do sal\u00e1rio de abril come\u00e7ou e muitos trabalhadores passaram a sentir no bolso a redu\u00e7\u00e3o dos ganhos em fun\u00e7\u00e3o da diminui\u00e7\u00e3o da jornada de trabalho. O governo vai ajudar, mas a complementa\u00e7\u00e3o n\u00e3o ser\u00e1 integral.<\/p>\n<p style=\"text-align: justify;\">O primeiro passo \u00e9 ficar de olho no patr\u00e3o. Se ele n\u00e3o avisar o governo que fez o acordo de redu\u00e7\u00e3o de jornada de trabalho ou de suspens\u00e3o do contrato no\u00a0<b>prazo de 10 dias,\u00a0<\/b>o empregado n\u00e3o vai receber o<b>\u00a0benef\u00edcio emergencial (BEm).<\/b><\/p>\n<p>Neste caso, o patr\u00e3o ter\u00e1 que pagar o sal\u00e1rio integral, sem qualquer redu\u00e7\u00e3o, ainda que o trabalhador tenha trabalhado menos.<\/p>\n<p style=\"text-align: justify;\">Se o patr\u00e3o fizer tudo direitinho, o empregado vai receber o benef\u00edcio no prazo de\u00a0<b>30 dias da data que assinou o acordo<\/b>. N\u00e3o vai ser no dia do pagamento. Ent\u00e3o fa\u00e7a as contas.<\/p>\n<p>O holerite pode ser menor nos pr\u00f3ximos tr\u00eas meses, com redu\u00e7\u00e3o de 25%, 50% ou 70%. Para compensar um pouco essa perda, o governo entrar\u00e1 com uma parte do sal\u00e1rio. Ela ser\u00e1 calculada sobre o que seria o valor do seguro-desemprego. Vai ser um pouco, n\u00e3o uma complementa\u00e7\u00e3o total.<\/p>\n<p style=\"text-align: justify;\">Aten\u00e7\u00e3o: o <b>valor do seguro-desemprego<\/b>\u00a0que vai servir de base para calcular o benef\u00edcio emergencial deve ser definido com\u00a0<b>base nos sal\u00e1rios dos \u00faltimos tr\u00eas meses<\/b>\u00a0do trabalhador. As horas extras, adicional noturno, de insalubridade, periculosidade, enfim,\u00a0<b>todas as vantagens salariais do empregado, entram nesta conta.<\/b><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 14pt;\">Onde e como vou receber?<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">O Minist\u00e9rio da Economia deu essa resposta. O<b>\u00a0trabalhador pode indicar<\/b>\u00a0ao empregador uma\u00a0<b>conta corrente ou conta poupan\u00e7a<\/b>\u00a0onde quer que o dep\u00f3sito seja feito. O BEm n\u00e3o ser\u00e1 pago em contas que n\u00e3o seja do empregado.<\/p>\n<p>Caso n\u00e3o seja informada uma conta ou haja erros na conta informada pelo empregador, o pagamento ser\u00e1 feito em uma\u00a0<b>conta digital aberta pelo Minist\u00e9rio da Economia<\/b>, em nome do trabalhador, junto ao\u00a0<b>Banco do Brasil<\/b>\u00a0ou \u00e0\u00a0<b>Caixa Econ\u00f4mica Federal.<\/b><\/p>\n<p style=\"text-align: justify;\">\n<span style=\"font-size: 14pt;\"><strong>Fraudes<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Tem patr\u00e3o que est\u00e1 reduzindo sal\u00e1rio e exigindo que o empregado continue trabalhando o mesmo ou at\u00e9 mais. Mas pense comigo:\u00a0<b>se o acordo \u00e9 para reduzir sal\u00e1rio, ent\u00e3o \u00e9 para trabalhar menos<\/b>. Ou at\u00e9 nem trabalhar se for o caso de suspens\u00e3o do contrato. Se isso n\u00e3o acontecer,\u00a0<b>denuncie ao Minist\u00e9rio da Economia<\/b>. Voc\u00ea n\u00e3o precisa nem se identificar. Ali\u00e1s, para quem pode, tamb\u00e9m \u00e9 hora de ficar em casa, protegido e quieto.<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 14pt;\">Se eu receber agora, perco se for demitido?<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Esse benef\u00edcio n\u00e3o tem nada a ver com o seguro-desemprego. Quem receber a compensa\u00e7\u00e3o decorrente da redu\u00e7\u00e3o do sal\u00e1rio em raz\u00e3o da diminui\u00e7\u00e3o da jornada n\u00e3o vai perder o seguro-desemprego se depois for demitido sem justa causa, por exemplo.<\/p>\n<p>Quem tiver que receber o seguro-desemprego por qualquer outro motivo previsto na lei continuar\u00e1 podendo receber. Isso est\u00e1 na medida provis\u00f3ria. Fique tranquilo.<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 14pt;\">N\u00e3o haver\u00e1 complementa\u00e7\u00e3o<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">O valor do sal\u00e1rio n\u00e3o vai ser complementado. O trabalhador pode e \u00e9 bem prov\u00e1vel que vai receber menos do que ganhava. Vai ter\u00a0<b>uma compensa\u00e7\u00e3o, n\u00e3o uma complementa\u00e7\u00e3o<\/b>.<\/p>\n<p>Quando houver redu\u00e7\u00e3o de jornada de trabalho e de sal\u00e1rio, a compensa\u00e7\u00e3o ser\u00e1 no mesmo percentual da redu\u00e7\u00e3o. Mas esse percentual n\u00e3o vai incidir sobre o valor do sal\u00e1rio, mas sim sobre o valor do que seria o seguro-desemprego.<\/p>\n<p style=\"text-align: justify;\">Por exemplo: se a redu\u00e7\u00e3o do sal\u00e1rio for de 25%, o benef\u00edcio emergencial ser\u00e1 de 25% do que seria o seguro-desemprego e n\u00e3o 25% do sal\u00e1rio. Por isso, o trabalhador pode ter uma redu\u00e7\u00e3o na renda.<\/p>\n<p>Quando houver suspens\u00e3o tempor\u00e1ria do contrato de trabalho, o valor do benef\u00edcio emergencial ser\u00e1 igual a 100% do seguro-desemprego. Pode ser de 70% quando a empresa tiver a obriga\u00e7\u00e3o de manter 30% do sal\u00e1rio.<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 14pt;\">E o valor da aposentadoria, como fica?<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Para quem vai ter o contrato suspenso, como n\u00e3o vai ter sal\u00e1rio, n\u00e3o haver\u00e1 contribui\u00e7\u00e3o. O governo autorizou quem quiser a pagar como desempregado. Quem est\u00e1 perto da aposentadoria sabe que qualquer dia de contribui\u00e7\u00e3o \u00e9 importante, ent\u00e3o \u00e9 bom pagar.<\/p>\n<p>Para quem vai ter redu\u00e7\u00e3o do sal\u00e1rio, a contribui\u00e7\u00e3o continuar\u00e1 sendo feita pelo patr\u00e3o, mas com valor menor. Voc\u00ea sabe, n\u00e3o \u00e9? Valor de contribui\u00e7\u00e3o menor significa aposentadoria menor, mas tamb\u00e9m n\u00e3o vai ser t\u00e3o menor assim, porque sempre \u00e9 feita uma m\u00e9dia das contribui\u00e7\u00f5es desde 1994. Ent\u00e3o dois ou tr\u00eas meses de contribui\u00e7\u00e3o baixa \u00e9 um pingo no oceano. N\u00e3o adianta gastar muito dinheiro agora, a Previd\u00eancia pode esperar um pouco. \u00c9 hora de cuidar da sa\u00fade.<\/p>\n<p style=\"text-align: justify;\">Fonte: Direito News (https:\/\/www.direitonews.com.br\/2020\/05\/beneficio-emergencial-empregado-olho-patrao-governo.html)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O pagamento do sal\u00e1rio de abril come\u00e7ou e muitos trabalhadores passaram a sentir no bolso a redu\u00e7\u00e3o dos ganhos em fun\u00e7\u00e3o da diminui\u00e7\u00e3o da jornada de trabalho. O governo vai ajudar, mas a complementa\u00e7\u00e3o n\u00e3o ser\u00e1 integral. O primeiro passo \u00e9 ficar de olho no patr\u00e3o. Se ele n\u00e3o avisar o governo que fez o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[7],"tags":[],"class_list":["post-2997","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.amaralfazla.com.br\/site\/wp-json\/wp\/v2\/posts\/2997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amaralfazla.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amaralfazla.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amaralfazla.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amaralfazla.com.br\/site\/wp-json\/wp\/v2\/comments?post=2997"}],"version-history":[{"count":0,"href":"https:\/\/www.amaralfazla.com.br\/site\/wp-json\/wp\/v2\/posts\/2997\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.amaralfazla.com.br\/site\/wp-json\/wp\/v2\/media?parent=2997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amaralfazla.com.br\/site\/wp-json\/wp\/v2\/categories?post=2997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amaralfazla.com.br\/site\/wp-json\/wp\/v2\/tags?post=2997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}