{"id":2993,"date":"2020-04-22T19:44:23","date_gmt":"2020-04-22T19:44:23","guid":{"rendered":"https:\/\/www.graphn.com.br\/amaralefazla\/plano-de-saude-nao-pode-cobrar-parcelas-durante-a-suspensao-do-contrato-por-inadimplencia\/"},"modified":"2020-04-22T19:44:23","modified_gmt":"2020-04-22T19:44:23","slug":"plano-de-saude-nao-pode-cobrar-parcelas-durante-a-suspensao-do-contrato-por-inadimplencia","status":"publish","type":"post","link":"https:\/\/www.amaralfazla.com.br\/site\/plano-de-saude-nao-pode-cobrar-parcelas-durante-a-suspensao-do-contrato-por-inadimplencia\/","title":{"rendered":"Plano de sa\u00fade n\u00e3o pode cobrar parcelas durante a suspens\u00e3o do contrato por inadimpl\u00eancia"},"content":{"rendered":"<p style=\"text-align: justify;\">Plano de sa\u00fade n\u00e3o pode cobrar parcelas durante a suspens\u00e3o do contrato por inadimplemento. Decis\u00e3o \u00e9 da 9\u00aa c\u00e2mara de Direito Privado do TJ\/SP ao negar provimento ao recurso do plano de sa\u00fade e concluir que, se h\u00e1 o cancelamento do plano por inadimpl\u00eancia, n\u00e3o h\u00e1 que se falar em pagamento de pr\u00eamio.<\/p>\n<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-1639 alignleft\" src=\"https:\/\/www.graphn.com.br\/amaralefazla\/wp-content\/uploads\/2023\/08\/Instagram-Amaral-Fazla-4-300x300.png\" alt=\"\" width=\"336\" height=\"336\" \/><\/p>\n<p style=\"text-align: justify;\">Consta nos autos que um segurado contratou os servi\u00e7os de seguro-sa\u00fade e ficou inadimplente. O plano foi automaticamente cancelado, mas apesar disso, o segurado passou a ser cobrado por pr\u00eamios devidos pelos 60 dias seguintes ao seu inadimplemento.<\/p>\n<p style=\"text-align: justify;\">O plano de sa\u00fade interp\u00f4s apela\u00e7\u00e3o contra senten\u00e7a que julgou procedente, embargos \u00e0 execu\u00e7\u00e3o, para o efeito de afastar o excesso de cobran\u00e7as de parcelas durante a suspens\u00e3o do contrato por inadimplemento.<\/p>\n<p style=\"text-align: justify;\">De acordo com a empresa, o prazo de continuidade do contrato de seguro sa\u00fade, na hip\u00f3tese de resili\u00e7\u00e3o, \u00e9 de dois meses, contados da efetiva den\u00fancia. Aduziu que o fato do segurado ter utilizado ou n\u00e3o os servi\u00e7os do plano de sa\u00fade, por si s\u00f3, n\u00e3o tem o cond\u00e3o de tornar a obriga\u00e7\u00e3o de arcar com os pr\u00eamios securit\u00e1rios inexig\u00edvel, pois os servi\u00e7os ainda lhe estavam dispon\u00edveis.<\/p>\n<p style=\"text-align: justify;\">Ao analisar o pedido da empresa, o desembargador Rog\u00e9rio Murillo Pereira Cimino, relator, verificou que o contrato acordado entre as partes prev\u00ea que o atraso no pagamento do pr\u00eamio mensal implicar\u00e1 na suspens\u00e3o autom\u00e1tica do direito \u00e0s coberturas do seguro a partir do 1\u00ba dia de inadimpl\u00eancia.<\/p>\n<p style=\"text-align: justify;\">Para o desembargador, suspensa a cobertura do seguro,\u00a0<em>\u201cn\u00e3o h\u00e1 que se falar em pagamento da parcela do pr\u00eamio, pois implicaria em enriquecimento il\u00edcito da parte embargada, ora apelante, o que \u00e9 vedado pelo ordenamento jur\u00eddico\u201d.<\/em><\/p>\n<p style=\"text-align: justify;\">Com este entendimento, o colegiado decidiu por manter a senten\u00e7a e afastar o excesso de execu\u00e7\u00e3o, correspondente \u00e0s parcelas cobradas ap\u00f3s a inadimpl\u00eancia.<\/p>\n<ul style=\"text-align: justify;\">\n<li>Processo:\u00a0<a href=\"https:\/\/esaj.tjsp.jus.br\/cposg\/search.do?conversationId=&amp;paginaConsulta=1&amp;localPesquisa.cdLocal=-1&amp;cbPesquisa=NUMPROC&amp;tipoNuProcesso=UNIFICADO&amp;numeroDigitoAnoUnificado=1023495-15.2017&amp;foroNumeroUnificado=0114&amp;dePesquisaNuUnificado=10234951520178260114&amp;dePesquisa=&amp;uuidCaptcha=sajcaptcha_7db390363e5544458d0bcbea49dded49&amp;g-recaptcha-response=03AGdBq24CN3THD0UnaUB1gYjXuxjN_8WVqrv5vwfumSLY5p_BHbUI_82PE_OMrxr8Ru0sIan8PkydY7eD78333rPNbPTNlx1jqlyeFK15MrDMhBJhQayqPDIJ9FJDn7EzDjxIbcD9_Jb6Xp6koS_QhmOYt0eRHqHmhAmoV764PSMgK_FdAcaar437Mc1lJuBR82dRLqw2BmyEaqUASerH4a-Z6EsPX6XJZi3trLt-adTHiLRSh1Ou9eETVGDAp6Zos5e8y8-XP4ngNsKvMYd1N3dI4iUhAKxkXMj_sbCVGDyNQz7nuLAB2ncYyuNnVHFfwcY65vxV0fi5djvr2hnUrt9CfBA_ztCZSjh5IjkGFx0PIBtluJCdlpmTTLDGL1jeEWfxM4EGtz0oF9c-1J1_m2vFuUi584t3qg\" target=\"_blank\" rel=\"noopener noreferrer\">1023495-15.2017.8.26.0114<\/a><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Veja o\u00a0<a href=\"https:\/\/www.migalhas.com.br\/arquivos\/2020\/4\/5E754C81CA6728_acorao_.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">ac\u00f3rd\u00e3o<\/a>.<\/p>\n<p style=\"text-align: justify;\">Fonte: Migalhas (https:\/\/migalhas.com.br\/quentes\/325199\/plano-de-saude-nao-pode-cobrar-parcelas-durante-a-suspensao-do-contrato-por-inadimplencia)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plano de sa\u00fade n\u00e3o pode cobrar parcelas durante a suspens\u00e3o do contrato por inadimplemento. Decis\u00e3o \u00e9 da 9\u00aa c\u00e2mara de Direito Privado do TJ\/SP ao negar provimento ao recurso do plano de sa\u00fade e concluir que, se h\u00e1 o cancelamento do plano por inadimpl\u00eancia, n\u00e3o h\u00e1 que se falar em pagamento de pr\u00eamio. Consta nos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2717,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[7],"tags":[],"class_list":["post-2993","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.amaralfazla.com.br\/site\/wp-json\/wp\/v2\/posts\/2993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amaralfazla.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amaralfazla.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amaralfazla.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amaralfazla.com.br\/site\/wp-json\/wp\/v2\/comments?post=2993"}],"version-history":[{"count":0,"href":"https:\/\/www.amaralfazla.com.br\/site\/wp-json\/wp\/v2\/posts\/2993\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amaralfazla.com.br\/site\/wp-json\/wp\/v2\/media\/2717"}],"wp:attachment":[{"href":"https:\/\/www.amaralfazla.com.br\/site\/wp-json\/wp\/v2\/media?parent=2993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amaralfazla.com.br\/site\/wp-json\/wp\/v2\/categories?post=2993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amaralfazla.com.br\/site\/wp-json\/wp\/v2\/tags?post=2993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}